{"id":1070,"count":1,"description":"","link":"https:\/\/www.voordeeluitjes.nl\/blog\/tag\/vissen\/","name":"Vissen","slug":"vissen","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vissen Archives - Vakantieblog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.voordeeluitjes.nl\/blog\/tag\/vissen\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vissen Archives - Vakantieblog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.voordeeluitjes.nl\/blog\/tag\/vissen\/\" \/>\n<meta property=\"og:site_name\" content=\"Vakantieblog\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.voordeeluitjes.nl\/blog\/tag\/vissen\/\",\"url\":\"https:\/\/www.voordeeluitjes.nl\/blog\/tag\/vissen\/\",\"name\":\"Vissen Archives - Vakantieblog\",\"isPartOf\":{\"@id\":\"https:\/\/www.voordeeluitjes.nl\/blog\/#website\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.voordeeluitjes.nl\/blog\/#website\",\"url\":\"https:\/\/www.voordeeluitjes.nl\/blog\/\",\"name\":\"Vakantieblog\",\"description\":\"Voordeeluitjes.nl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.voordeeluitjes.nl\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vissen Archives - Vakantieblog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.voordeeluitjes.nl\/blog\/tag\/vissen\/","og_locale":"nl_NL","og_type":"article","og_title":"Vissen Archives - Vakantieblog","og_url":"https:\/\/www.voordeeluitjes.nl\/blog\/tag\/vissen\/","og_site_name":"Vakantieblog","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.voordeeluitjes.nl\/blog\/tag\/vissen\/","url":"https:\/\/www.voordeeluitjes.nl\/blog\/tag\/vissen\/","name":"Vissen Archives - Vakantieblog","isPartOf":{"@id":"https:\/\/www.voordeeluitjes.nl\/blog\/#website"},"inLanguage":"nl-NL"},{"@type":"WebSite","@id":"https:\/\/www.voordeeluitjes.nl\/blog\/#website","url":"https:\/\/www.voordeeluitjes.nl\/blog\/","name":"Vakantieblog","description":"Voordeeluitjes.nl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.voordeeluitjes.nl\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/www.voordeeluitjes.nl\/blog\/wp-json\/wp\/v2\/tags\/1070"}],"collection":[{"href":"https:\/\/www.voordeeluitjes.nl\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.voordeeluitjes.nl\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.voordeeluitjes.nl\/blog\/wp-json\/wp\/v2\/posts?tags=1070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}